{"id":6215,"date":"2012-12-21T13:52:44","date_gmt":"2012-12-21T12:52:44","guid":{"rendered":"https:\/\/dev.servicemanualsgsxr.com\/?p=27146"},"modified":"2012-12-21T13:52:44","modified_gmt":"2012-12-21T12:52:44","slug":"nuevos-tatuajes-de-suzuki-encontrados-en-google","status":"publish","type":"post","link":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/tatuajes\/nuevos-tatuajes-de-suzuki-encontrados-en-google\/","title":{"rendered":"Nuevos tatuajes de Suzuki encontrados en Google"},"content":{"rendered":"<p style=\"text-align: justify;\">Desde Mayo que no hac\u00eda un recopilatorio de fotograf\u00edas con tatuajes y de tem\u00e1tica el mundo Suzuki, as\u00ed que me dado una vuelta por <strong>Google<\/strong> a ver qu\u00e9 encontraba y me ha sorprendido ver algunos tatuajes muy bien elaborados.<\/p>\n<p style=\"text-align: justify;\">El tatuaje de la <strong>Suzuki GSX-R 1000 2011<\/strong> est\u00e1 muy bien hecho, creo que de lo mejorcito que he visto en colores \u00faltimamente. El de la <strong>Suzuki GSX-R 1000<\/strong> en la espalda, es que est\u00e1 de frente, es brutal, un trabajo tremendo. En cambio el de la <strong>Suzuki GSX-R 1000 2007<\/strong> en negro, no me gusta tanto.<\/p>\n<p style=\"text-align: justify;\">El de la Suzuki GSX-R haciendo el caballito sobre el frontal de la moto y frente a la muerte, es super simp\u00e1tico, sobre todo si os fijais que el piloto es el mismo compa\u00f1ero tatuado con su propio tatuaje, es buenisimo.<\/p>\n<p style=\"text-align: justify;\">El tatuaje de<strong> Kevin Schwantz<\/strong> con su moto <strong>Suzuki RGV 500 Pepsi<\/strong> y encima con la firma por encima, eso no tiene nombre, me ha encantado.<\/p>\n<p style=\"text-align: justify;\">Finalmente os pongo un tatuaje que me ha gustado realmente, por el efecto que ha hecho, como si le rasgara la piel, el del <strong>Quad Suzuki<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Todos ellos igualmente muy currados y de gran vistosidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde Mayo que no hac\u00eda un recopilatorio de fotograf\u00edas con tatuajes y de tem\u00e1tica el mundo Suzuki, as\u00ed que me dado una vuelta por Google a ver qu\u00e9 encontraba y me ha sorprendido ver algunos tatuajes muy bien elaborados. El tatuaje de la Suzuki GSX-R 1000 2011 est\u00e1 muy bien hecho, creo que de lo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6216,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[275],"tags":[90,14,41,331],"class_list":["post-6215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tatuajes","tag-kevin-schwantz","tag-suzuki","tag-suzuki-gsx-r-1000-2007","tag-tatuajes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuevos tatuajes de Suzuki encontrados en Google | Motocicletas Suzuki<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/tatuajes\/nuevos-tatuajes-de-suzuki-encontrados-en-google\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuevos tatuajes de Suzuki encontrados en Google | Motocicletas Suzuki\" \/>\n<meta property=\"og:description\" content=\"Desde Mayo que no hac\u00eda un recopilatorio de fotograf\u00edas con tatuajes y de tem\u00e1tica el mundo Suzuki, as\u00ed que me dado una vuelta por Google a ver qu\u00e9 encontraba y me ha sorprendido ver algunos tatuajes muy bien elaborados. El tatuaje de la Suzuki GSX-R 1000 2011 est\u00e1 muy bien hecho, creo que de lo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/tatuajes\/nuevos-tatuajes-de-suzuki-encontrados-en-google\/\" \/>\n<meta property=\"og:site_name\" content=\"Motocicletas Suzuki\" \/>\n<meta property=\"article:published_time\" content=\"2012-12-21T12:52:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2023\/09\/suzuki-motorcycles-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" \/>\n\t<meta property=\"og:image:height\" content=\"126\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Suzuki Motocicletas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Suzuki Motocicletas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/tatuajes\\\/nuevos-tatuajes-de-suzuki-encontrados-en-google\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/tatuajes\\\/nuevos-tatuajes-de-suzuki-encontrados-en-google\\\/\"},\"author\":{\"name\":\"Suzuki Motocicletas\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#\\\/schema\\\/person\\\/b2452f1f1c397049f68165f3dd829646\"},\"headline\":\"Nuevos tatuajes de Suzuki encontrados en Google\",\"datePublished\":\"2012-12-21T12:52:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/tatuajes\\\/nuevos-tatuajes-de-suzuki-encontrados-en-google\\\/\"},\"wordCount\":204,\"publisher\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/tatuajes\\\/nuevos-tatuajes-de-suzuki-encontrados-en-google\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/tatuaje-suzuki-gsxr-1000-2011.jpg\",\"keywords\":[\"kevin schwantz\",\"Suzuki\",\"Suzuki GSX-R 1000 2007\",\"tatuajes\"],\"articleSection\":[\"Tatuajes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/tatuajes\\\/nuevos-tatuajes-de-suzuki-encontrados-en-google\\\/\",\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/tatuajes\\\/nuevos-tatuajes-de-suzuki-encontrados-en-google\\\/\",\"name\":\"Nuevos tatuajes de Suzuki encontrados en Google | Motocicletas Suzuki\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/tatuajes\\\/nuevos-tatuajes-de-suzuki-encontrados-en-google\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/tatuajes\\\/nuevos-tatuajes-de-suzuki-encontrados-en-google\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/tatuaje-suzuki-gsxr-1000-2011.jpg\",\"datePublished\":\"2012-12-21T12:52:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/tatuajes\\\/nuevos-tatuajes-de-suzuki-encontrados-en-google\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/tatuajes\\\/nuevos-tatuajes-de-suzuki-encontrados-en-google\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/tatuajes\\\/nuevos-tatuajes-de-suzuki-encontrados-en-google\\\/#primaryimage\",\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/tatuaje-suzuki-gsxr-1000-2011.jpg\",\"contentUrl\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/tatuaje-suzuki-gsxr-1000-2011.jpg\",\"width\":800,\"height\":600,\"caption\":\"Tatuaje Suzuki GSX-R 1000 2011\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/tatuajes\\\/nuevos-tatuajes-de-suzuki-encontrados-en-google\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuevos tatuajes de Suzuki encontrados en Google\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/\",\"name\":\"Motocicletas Suzuki\",\"description\":\"Noticias, informaci\u00f3n y fichas t\u00e9cnicas de motocicletas Suzuki en los modelos deportivas, carretera, trail sport turismo, scooter, cruiser, motocross y enduro\",\"publisher\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#organization\",\"name\":\"Motocicletas Suzuki\",\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/suzuki-motorcycles-logo.png\",\"contentUrl\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/suzuki-motorcycles-logo.png\",\"width\":670,\"height\":126,\"caption\":\"Motocicletas Suzuki\"},\"image\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#\\\/schema\\\/person\\\/b2452f1f1c397049f68165f3dd829646\",\"name\":\"Suzuki Motocicletas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g\",\"caption\":\"Suzuki Motocicletas\"},\"sameAs\":[\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\"],\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/author\\\/root\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuevos tatuajes de Suzuki encontrados en Google | Motocicletas Suzuki","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/tatuajes\/nuevos-tatuajes-de-suzuki-encontrados-en-google\/","og_locale":"es_ES","og_type":"article","og_title":"Nuevos tatuajes de Suzuki encontrados en Google | Motocicletas Suzuki","og_description":"Desde Mayo que no hac\u00eda un recopilatorio de fotograf\u00edas con tatuajes y de tem\u00e1tica el mundo Suzuki, as\u00ed que me dado una vuelta por Google a ver qu\u00e9 encontraba y me ha sorprendido ver algunos tatuajes muy bien elaborados. El tatuaje de la Suzuki GSX-R 1000 2011 est\u00e1 muy bien hecho, creo que de lo [&hellip;]","og_url":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/tatuajes\/nuevos-tatuajes-de-suzuki-encontrados-en-google\/","og_site_name":"Motocicletas Suzuki","article_published_time":"2012-12-21T12:52:44+00:00","og_image":[{"width":670,"height":126,"url":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2023\/09\/suzuki-motorcycles-logo.png","type":"image\/png"}],"author":"Suzuki Motocicletas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Suzuki Motocicletas","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/tatuajes\/nuevos-tatuajes-de-suzuki-encontrados-en-google\/#article","isPartOf":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/tatuajes\/nuevos-tatuajes-de-suzuki-encontrados-en-google\/"},"author":{"name":"Suzuki Motocicletas","@id":"https:\/\/servicemanualsgsxr.com\/es\/#\/schema\/person\/b2452f1f1c397049f68165f3dd829646"},"headline":"Nuevos tatuajes de Suzuki encontrados en Google","datePublished":"2012-12-21T12:52:44+00:00","mainEntityOfPage":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/tatuajes\/nuevos-tatuajes-de-suzuki-encontrados-en-google\/"},"wordCount":204,"publisher":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/#organization"},"image":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/tatuajes\/nuevos-tatuajes-de-suzuki-encontrados-en-google\/#primaryimage"},"thumbnailUrl":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2012\/12\/tatuaje-suzuki-gsxr-1000-2011.jpg","keywords":["kevin schwantz","Suzuki","Suzuki GSX-R 1000 2007","tatuajes"],"articleSection":["Tatuajes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/tatuajes\/nuevos-tatuajes-de-suzuki-encontrados-en-google\/","url":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/tatuajes\/nuevos-tatuajes-de-suzuki-encontrados-en-google\/","name":"Nuevos tatuajes de Suzuki encontrados en Google | Motocicletas Suzuki","isPartOf":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/tatuajes\/nuevos-tatuajes-de-suzuki-encontrados-en-google\/#primaryimage"},"image":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/tatuajes\/nuevos-tatuajes-de-suzuki-encontrados-en-google\/#primaryimage"},"thumbnailUrl":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2012\/12\/tatuaje-suzuki-gsxr-1000-2011.jpg","datePublished":"2012-12-21T12:52:44+00:00","breadcrumb":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/tatuajes\/nuevos-tatuajes-de-suzuki-encontrados-en-google\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/tatuajes\/nuevos-tatuajes-de-suzuki-encontrados-en-google\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/tatuajes\/nuevos-tatuajes-de-suzuki-encontrados-en-google\/#primaryimage","url":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2012\/12\/tatuaje-suzuki-gsxr-1000-2011.jpg","contentUrl":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2012\/12\/tatuaje-suzuki-gsxr-1000-2011.jpg","width":800,"height":600,"caption":"Tatuaje Suzuki GSX-R 1000 2011"},{"@type":"BreadcrumbList","@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/tatuajes\/nuevos-tatuajes-de-suzuki-encontrados-en-google\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/servicemanualsgsxr.com\/es\/"},{"@type":"ListItem","position":2,"name":"Nuevos tatuajes de Suzuki encontrados en Google"}]},{"@type":"WebSite","@id":"https:\/\/servicemanualsgsxr.com\/es\/#website","url":"https:\/\/servicemanualsgsxr.com\/es\/","name":"Motocicletas Suzuki","description":"Noticias, informaci\u00f3n y fichas t\u00e9cnicas de motocicletas Suzuki en los modelos deportivas, carretera, trail sport turismo, scooter, cruiser, motocross y enduro","publisher":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/servicemanualsgsxr.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/servicemanualsgsxr.com\/es\/#organization","name":"Motocicletas Suzuki","url":"https:\/\/servicemanualsgsxr.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/servicemanualsgsxr.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2023\/09\/suzuki-motorcycles-logo.png","contentUrl":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2023\/09\/suzuki-motorcycles-logo.png","width":670,"height":126,"caption":"Motocicletas Suzuki"},"image":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/servicemanualsgsxr.com\/es\/#\/schema\/person\/b2452f1f1c397049f68165f3dd829646","name":"Suzuki Motocicletas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g","caption":"Suzuki Motocicletas"},"sameAs":["https:\/\/servicemanualsgsxr.com\/es"],"url":"https:\/\/servicemanualsgsxr.com\/es\/author\/root\/"}]}},"_links":{"self":[{"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/posts\/6215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/comments?post=6215"}],"version-history":[{"count":0,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/posts\/6215\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/media\/6216"}],"wp:attachment":[{"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/media?parent=6215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/categories?post=6215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/tags?post=6215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}