{"id":5925,"date":"2012-07-18T11:00:00","date_gmt":"2012-07-18T09:00:00","guid":{"rendered":"https:\/\/dev.servicemanualsgsxr.com\/?p=24311"},"modified":"2012-07-18T11:00:00","modified_gmt":"2012-07-18T09:00:00","slug":"no-hay-edad-para-dejar-de-conducir-motos","status":"publish","type":"post","link":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/no-hay-edad-para-dejar-de-conducir-motos\/","title":{"rendered":"No hay edad para dejar de conducir motos"},"content":{"rendered":"<p style=\"text-align: justify;\">No hay edad para dejar de conducir motos, no creo que la haya habido nunca y creo que no la habr\u00e1 jam\u00e1s. La afici\u00f3n por la moto va m\u00e1s all\u00e1 de edades y no s\u00f3lo eso, va m\u00e1s all\u00e1 de modelos y tipos de moto, como lo muestra esta pareja, con su moto <strong>Suzuki GSX-R 1000<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Hace unos dias saltaba la noticia en prensa de que un octogenario se hab\u00eda comprado una moto <strong>Ducati 1199 Panigale S<\/strong>. Aunque personas como estas las vemos en la calle a diario, y nos sigue sorprendiendo. Pero si tienes ya una cierta edad te va sorprendiendo menos.<\/p>\n<p style=\"text-align: justify;\">Yo pertenezco a un grupo de \u00abpuretas\u00bb que andamos con motos de 1000 cc y nos reimos imaginandonos a nosotros mismos dentro de 20 a\u00f1os con los monos reventados, el pelo canoso (para los que les queden pelos), llevando motos de no s\u00e9 cuantas cilindradas y siendo unos \u00abquemados\u00bb como hemos sido siempre.<\/p>\n<p style=\"text-align: justify;\">La afici\u00f3n de la moto se lleva y se llevar\u00e1 siempre en el coraz\u00f3n, puede que eso nos haga seguir siendo siempre j\u00f3venes&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No hay edad para dejar de conducir motos, no creo que la haya habido nunca y creo que no la habr\u00e1 jam\u00e1s. La afici\u00f3n por la moto va m\u00e1s all\u00e1 de edades y no s\u00f3lo eso, va m\u00e1s all\u00e1 de modelos y tipos de moto, como lo muestra esta pareja, con su moto Suzuki GSX-R [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5926,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[14,16],"class_list":["post-5925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-motos","tag-suzuki","tag-suzuki-gsx-r-1000"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>No hay edad para dejar de conducir motos | Motocicletas Suzuki<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/no-hay-edad-para-dejar-de-conducir-motos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No hay edad para dejar de conducir motos | Motocicletas Suzuki\" \/>\n<meta property=\"og:description\" content=\"No hay edad para dejar de conducir motos, no creo que la haya habido nunca y creo que no la habr\u00e1 jam\u00e1s. La afici\u00f3n por la moto va m\u00e1s all\u00e1 de edades y no s\u00f3lo eso, va m\u00e1s all\u00e1 de modelos y tipos de moto, como lo muestra esta pareja, con su moto Suzuki GSX-R [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/no-hay-edad-para-dejar-de-conducir-motos\/\" \/>\n<meta property=\"og:site_name\" content=\"Motocicletas Suzuki\" \/>\n<meta property=\"article:published_time\" content=\"2012-07-18T09:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2023\/09\/suzuki-motorcycles-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" \/>\n\t<meta property=\"og:image:height\" content=\"126\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Suzuki Motocicletas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Suzuki Motocicletas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/no-hay-edad-para-dejar-de-conducir-motos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/no-hay-edad-para-dejar-de-conducir-motos\\\/\"},\"author\":{\"name\":\"Suzuki Motocicletas\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#\\\/schema\\\/person\\\/b2452f1f1c397049f68165f3dd829646\"},\"headline\":\"No hay edad para dejar de conducir motos\",\"datePublished\":\"2012-07-18T09:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/no-hay-edad-para-dejar-de-conducir-motos\\\/\"},\"wordCount\":193,\"publisher\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/no-hay-edad-para-dejar-de-conducir-motos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2012\\\/07\\\/conductores-mayores-en-moto.jpg\",\"keywords\":[\"Suzuki\",\"Suzuki GSX-R 1000\"],\"articleSection\":[\"Motos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/no-hay-edad-para-dejar-de-conducir-motos\\\/\",\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/no-hay-edad-para-dejar-de-conducir-motos\\\/\",\"name\":\"No hay edad para dejar de conducir motos | Motocicletas Suzuki\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/no-hay-edad-para-dejar-de-conducir-motos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/no-hay-edad-para-dejar-de-conducir-motos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2012\\\/07\\\/conductores-mayores-en-moto.jpg\",\"datePublished\":\"2012-07-18T09:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/no-hay-edad-para-dejar-de-conducir-motos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/no-hay-edad-para-dejar-de-conducir-motos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/no-hay-edad-para-dejar-de-conducir-motos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2012\\\/07\\\/conductores-mayores-en-moto.jpg\",\"contentUrl\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2012\\\/07\\\/conductores-mayores-en-moto.jpg\",\"width\":720,\"height\":625,\"caption\":\"conductores mayores en moto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/no-hay-edad-para-dejar-de-conducir-motos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"No hay edad para dejar de conducir motos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/\",\"name\":\"Motocicletas Suzuki\",\"description\":\"Noticias, informaci\u00f3n y fichas t\u00e9cnicas de motocicletas Suzuki en los modelos deportivas, carretera, trail sport turismo, scooter, cruiser, motocross y enduro\",\"publisher\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#organization\",\"name\":\"Motocicletas Suzuki\",\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/suzuki-motorcycles-logo.png\",\"contentUrl\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/suzuki-motorcycles-logo.png\",\"width\":670,\"height\":126,\"caption\":\"Motocicletas Suzuki\"},\"image\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#\\\/schema\\\/person\\\/b2452f1f1c397049f68165f3dd829646\",\"name\":\"Suzuki Motocicletas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g\",\"caption\":\"Suzuki Motocicletas\"},\"sameAs\":[\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\"],\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/author\\\/root\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"No hay edad para dejar de conducir motos | Motocicletas Suzuki","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/no-hay-edad-para-dejar-de-conducir-motos\/","og_locale":"es_ES","og_type":"article","og_title":"No hay edad para dejar de conducir motos | Motocicletas Suzuki","og_description":"No hay edad para dejar de conducir motos, no creo que la haya habido nunca y creo que no la habr\u00e1 jam\u00e1s. La afici\u00f3n por la moto va m\u00e1s all\u00e1 de edades y no s\u00f3lo eso, va m\u00e1s all\u00e1 de modelos y tipos de moto, como lo muestra esta pareja, con su moto Suzuki GSX-R [&hellip;]","og_url":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/no-hay-edad-para-dejar-de-conducir-motos\/","og_site_name":"Motocicletas Suzuki","article_published_time":"2012-07-18T09:00:00+00:00","og_image":[{"width":670,"height":126,"url":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2023\/09\/suzuki-motorcycles-logo.png","type":"image\/png"}],"author":"Suzuki Motocicletas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Suzuki Motocicletas","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/no-hay-edad-para-dejar-de-conducir-motos\/#article","isPartOf":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/no-hay-edad-para-dejar-de-conducir-motos\/"},"author":{"name":"Suzuki Motocicletas","@id":"https:\/\/servicemanualsgsxr.com\/es\/#\/schema\/person\/b2452f1f1c397049f68165f3dd829646"},"headline":"No hay edad para dejar de conducir motos","datePublished":"2012-07-18T09:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/no-hay-edad-para-dejar-de-conducir-motos\/"},"wordCount":193,"publisher":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/#organization"},"image":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/no-hay-edad-para-dejar-de-conducir-motos\/#primaryimage"},"thumbnailUrl":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2012\/07\/conductores-mayores-en-moto.jpg","keywords":["Suzuki","Suzuki GSX-R 1000"],"articleSection":["Motos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/no-hay-edad-para-dejar-de-conducir-motos\/","url":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/no-hay-edad-para-dejar-de-conducir-motos\/","name":"No hay edad para dejar de conducir motos | Motocicletas Suzuki","isPartOf":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/no-hay-edad-para-dejar-de-conducir-motos\/#primaryimage"},"image":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/no-hay-edad-para-dejar-de-conducir-motos\/#primaryimage"},"thumbnailUrl":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2012\/07\/conductores-mayores-en-moto.jpg","datePublished":"2012-07-18T09:00:00+00:00","breadcrumb":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/no-hay-edad-para-dejar-de-conducir-motos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/no-hay-edad-para-dejar-de-conducir-motos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/no-hay-edad-para-dejar-de-conducir-motos\/#primaryimage","url":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2012\/07\/conductores-mayores-en-moto.jpg","contentUrl":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2012\/07\/conductores-mayores-en-moto.jpg","width":720,"height":625,"caption":"conductores mayores en moto"},{"@type":"BreadcrumbList","@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/no-hay-edad-para-dejar-de-conducir-motos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/servicemanualsgsxr.com\/es\/"},{"@type":"ListItem","position":2,"name":"No hay edad para dejar de conducir motos"}]},{"@type":"WebSite","@id":"https:\/\/servicemanualsgsxr.com\/es\/#website","url":"https:\/\/servicemanualsgsxr.com\/es\/","name":"Motocicletas Suzuki","description":"Noticias, informaci\u00f3n y fichas t\u00e9cnicas de motocicletas Suzuki en los modelos deportivas, carretera, trail sport turismo, scooter, cruiser, motocross y enduro","publisher":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/servicemanualsgsxr.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/servicemanualsgsxr.com\/es\/#organization","name":"Motocicletas Suzuki","url":"https:\/\/servicemanualsgsxr.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/servicemanualsgsxr.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2023\/09\/suzuki-motorcycles-logo.png","contentUrl":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2023\/09\/suzuki-motorcycles-logo.png","width":670,"height":126,"caption":"Motocicletas Suzuki"},"image":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/servicemanualsgsxr.com\/es\/#\/schema\/person\/b2452f1f1c397049f68165f3dd829646","name":"Suzuki Motocicletas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g","caption":"Suzuki Motocicletas"},"sameAs":["https:\/\/servicemanualsgsxr.com\/es"],"url":"https:\/\/servicemanualsgsxr.com\/es\/author\/root\/"}]}},"_links":{"self":[{"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/posts\/5925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/comments?post=5925"}],"version-history":[{"count":0,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/posts\/5925\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/media\/5926"}],"wp:attachment":[{"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/media?parent=5925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/categories?post=5925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/tags?post=5925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}