{"id":5168,"date":"2011-06-02T20:49:29","date_gmt":"2011-06-02T18:49:29","guid":{"rendered":"https:\/\/dev.servicemanualsgsxr.com\/?p=20379"},"modified":"2011-06-02T20:49:29","modified_gmt":"2011-06-02T18:49:29","slug":"chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie","status":"publish","type":"post","link":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\/","title":{"rendered":"Chaqueta de moto Suzuki en la pelicula Hackers con Angelina Jolie"},"content":{"rendered":"<p style=\"text-align: justify;\">La semana pasada volvieron a pasar por televisi\u00f3n la pel\u00edcula de cine <a title=\"Pelicula Hackers con Angelina Jolie\" href=\"http:\/\/es.wikipedia.org\/wiki\/Hackers_%28pel%C3%ADcula%29\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Hackers<\/strong><\/a> con <strong>Angelina Jolie<\/strong> y <strong>Jonny Lee Miller<\/strong>. Al volver a verla me acord\u00e9 de que el a\u00f1o pasado estuve buscando informaci\u00f3n sobre la <strong>chaqueta de moto<\/strong> que lleva <strong>Angelina Jolie<\/strong> casi a mitad de la pel\u00edcula.<\/p>\n<p style=\"text-align: justify;\">La informaci\u00f3n que encontr\u00e9 ven\u00eda de la <a title=\"Dise\u00f1adora vestuario pelicula Hackers\" href=\"http:\/\/www.yourprops.com\/view_item.php?movie_prop=10347\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>dise\u00f1adora de vestuario<\/strong><\/a> de la pel\u00edcula, que contaba c\u00f3mo hab\u00eda conseguido la chaqueta, en un mercado callejero de new york y que le hab\u00eda costado unos d\u00f3lares.<\/p>\n<p style=\"text-align: justify;\">El caso es que la dise\u00f1adora no sab\u00eda ni qu\u00e9 ten\u00eda en las manos, ni de d\u00f3nde proven\u00eda, s\u00f3lo sab\u00eda que la chaqueta de moto era muy \u00abcool\u00bb.<\/p>\n<p style=\"text-align: justify;\">A mi me extra\u00f1\u00f3 bastante el tema, sobre todo porque para los que entendemos un poco de motos y de carreras, la primera imagen que te viene a la cabeza cuando ves la chaqueta de moto, es la imagen del fant\u00e1stico piloto brit\u00e1nico del equipo Suzuki en los a\u00f1os 80&#8217;s, <a title=\"Piloto motociclismo Barry Sheene\" href=\"http:\/\/en.wikipedia.org\/wiki\/Barry_Sheene\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Barry Sheene<\/strong><\/a>, que llevaba esos colores y esa decoraci\u00f3n en su moto y en su mono.<\/p>\n<p style=\"text-align: justify;\">Colores adoptados de su patrocinador en esa \u00e9poca, la empresa petrolera <a title=\"Texaco empresa petrolera\" href=\"http:\/\/es.wikipedia.org\/wiki\/Texaco\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Texaco<\/strong><\/a>, que hoy en d\u00eda sigue utilizando los colores rojo y negro en su imagen corporativa y la uni\u00f3n con la compa\u00f1\u00eda <a title=\"Heron International\" href=\"http:\/\/en.wikipedia.org\/wiki\/Heron_International\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Heron International<\/strong><\/a> y <strong>Suzuki<\/strong>, formando el equipo <strong>Texaco Heron Team Suzuki<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Aunque la chaqueta de la pel\u00edcula s\u00f3lo lleva el logotipo simple de la S de Suzuki en el pecho, el mono de <strong>Barry Sheene<\/strong> tambi\u00e9n tenia el logotipo completo en los brazos, el numero 7 en los hombros y en la espalda junto a su apellido.<\/p>\n<p style=\"text-align: justify;\">As\u00ed que esa chaqueta adem\u00e1s de ser \u00fanica, era una versi\u00f3n que cualquiera sabe de d\u00f3nde saldr\u00eda (a no ser que le quitaran cosas, que no lo parece).<\/p>\n<p style=\"text-align: justify;\">La chaqueta de moto de la pel\u00edcula termin\u00f3, como siempre, vendi\u00e9ndose al mejor postor en una subasta online (no en ebay, la misma dise\u00f1adora de vestuario de la pel\u00edcula, ten\u00eda guardado m\u00e1s material de esas y otras pel\u00edculas y las fue vendiendo en una web).<\/p>\n<p style=\"text-align: justify;\"><strong>Barry Sheene <\/strong>muri\u00f3 en el 2003 de un c\u00e1ncer de est\u00f3mago aunque estaba tocado de un accidente grave en 1982 y que le apart\u00f3 de las carreras en 1984.<\/p>\n<p style=\"text-align: justify;\">En el a\u00f1o 2005, Suzuki lanzaba una serie limitada para conmemorar el 20 aniversario de la saga GSXR por todo el mundo (la <a title=\"Suzuki GSXR 750 2005 20 Aniversario\" href=\"https:\/\/servicemanualsgsxr.com\/es\/2010\/11\/29\/suzuki-gsx-r-750-2005-20th-anniversary\/\"><strong>Suzuki GSXR 750 20 Aniversario<\/strong><\/a>), pero en el Reino Unido se lanz\u00f3 una serie especial de venta s\u00f3lo en este pa\u00eds. Una <strong>Suzuki GSXR 750 Barry Sheene r\u00e9plica<\/strong>, una moto igual que la de serie pero con la particularidad de llevar un carenado r\u00e9plica a la moto de Barry Sheene con las llantas doradas. Motos de serie limitada r\u00e9plicas de la moto Suzuki GSR 500 que pilotara Barry Sheene durante el campeonato del mundo de velocidad en la categor\u00eda de 500 cc.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s se lanz\u00f3 una gran campa\u00f1a de merchandising con cazadoras, chaquetas de moto, camisetas, polos, camisas y dem\u00e1s material publicitario que tuvo muy buena y mucha aceptaci\u00f3n en el p\u00fablico brit\u00e1nico, que es donde tiene su mayor fila de seguidores este m\u00edtico piloto.<\/p>\n<p style=\"text-align: justify;\">Posteriormente se han hecho nuevos tributos a este gran piloto. Como hiciera <strong>Chris Vermeulen<\/strong> en el circuito de Australia, decorando su moto <strong>Suzuki GSV-R<\/strong> con los colores que llevara anteriormente <strong>Barry Sheene<\/strong>, en su \u00e9poca con la decoraci\u00f3n azul y blanco m\u00e1s t\u00edpica de la f\u00e1brica Suzuki.<\/p>\n<p style=\"text-align: justify;\">En fin, que uno v\u00e9 una chaqueta de moto en una pel\u00edcula, se informa y empieza a tirar del hilo, encontr\u00e1ndose viejas historias de pilotos tan grandes como el brit\u00e1nico <strong>Barry Sheene<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Por cierto y para dejaros pensando en el tema: sab\u00e9is que ese saludo motero que solemos hacer, el de los dedos en forma de V, cuando nos cruzamos con otro motero por la carretera, es original de Barry Sheene???<\/p>\n<p style=\"text-align: justify;\">Pues s\u00ed, este piloto sol\u00eda entrar en meta y levantaba la mano con los dedos en V, marcando con ello una de sus nuevas victorias. Eso pas\u00f3 al p\u00fablico y a la calle. As\u00ed que la pr\u00f3xima vez que saludes, recuerda que detr\u00e1s de ese s\u00edmbolo con los dedos hay una gran historia del motociclismo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La semana pasada volvieron a pasar por televisi\u00f3n la pel\u00edcula de cine Hackers con Angelina Jolie y Jonny Lee Miller. Al volver a verla me acord\u00e9 de que el a\u00f1o pasado estuve buscando informaci\u00f3n sobre la chaqueta de moto que lleva Angelina Jolie casi a mitad de la pel\u00edcula. La informaci\u00f3n que encontr\u00e9 ven\u00eda de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5177,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[247,305],"tags":[92],"class_list":["post-5168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades","category-suzuki-en-el-cine","tag-barry-sheene"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chaqueta de moto Suzuki en la pelicula Hackers con Angelina Jolie | Motocicletas Suzuki<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chaqueta de moto Suzuki en la pelicula Hackers con Angelina Jolie | Motocicletas Suzuki\" \/>\n<meta property=\"og:description\" content=\"La semana pasada volvieron a pasar por televisi\u00f3n la pel\u00edcula de cine Hackers con Angelina Jolie y Jonny Lee Miller. Al volver a verla me acord\u00e9 de que el a\u00f1o pasado estuve buscando informaci\u00f3n sobre la chaqueta de moto que lleva Angelina Jolie casi a mitad de la pel\u00edcula. La informaci\u00f3n que encontr\u00e9 ven\u00eda de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\/\" \/>\n<meta property=\"og:site_name\" content=\"Motocicletas Suzuki\" \/>\n<meta property=\"article:published_time\" content=\"2011-06-02T18:49:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2023\/09\/suzuki-motorcycles-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" \/>\n\t<meta property=\"og:image:height\" content=\"126\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Suzuki Motocicletas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Suzuki Motocicletas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\\\/\"},\"author\":{\"name\":\"Suzuki Motocicletas\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#\\\/schema\\\/person\\\/b2452f1f1c397049f68165f3dd829646\"},\"headline\":\"Chaqueta de moto Suzuki en la pelicula Hackers con Angelina Jolie\",\"datePublished\":\"2011-06-02T18:49:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\\\/\"},\"wordCount\":760,\"publisher\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/angelina-jolie-hackers-3.jpg\",\"keywords\":[\"barry sheene\"],\"articleSection\":[\"Curiosos\",\"Suzuki en el cine\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\\\/\",\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\\\/\",\"name\":\"Chaqueta de moto Suzuki en la pelicula Hackers con Angelina Jolie | Motocicletas Suzuki\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/angelina-jolie-hackers-3.jpg\",\"datePublished\":\"2011-06-02T18:49:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/angelina-jolie-hackers-3.jpg\",\"contentUrl\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/angelina-jolie-hackers-3.jpg\",\"width\":800,\"height\":523,\"caption\":\"Angelina Jolie en la pelicula Hackers\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chaqueta de moto Suzuki en la pelicula Hackers con Angelina Jolie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/\",\"name\":\"Motocicletas Suzuki\",\"description\":\"Noticias, informaci\u00f3n y fichas t\u00e9cnicas de motocicletas Suzuki en los modelos deportivas, carretera, trail sport turismo, scooter, cruiser, motocross y enduro\",\"publisher\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#organization\",\"name\":\"Motocicletas Suzuki\",\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/suzuki-motorcycles-logo.png\",\"contentUrl\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/suzuki-motorcycles-logo.png\",\"width\":670,\"height\":126,\"caption\":\"Motocicletas Suzuki\"},\"image\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#\\\/schema\\\/person\\\/b2452f1f1c397049f68165f3dd829646\",\"name\":\"Suzuki Motocicletas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g\",\"caption\":\"Suzuki Motocicletas\"},\"sameAs\":[\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\"],\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/author\\\/root\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chaqueta de moto Suzuki en la pelicula Hackers con Angelina Jolie | Motocicletas Suzuki","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\/","og_locale":"es_ES","og_type":"article","og_title":"Chaqueta de moto Suzuki en la pelicula Hackers con Angelina Jolie | Motocicletas Suzuki","og_description":"La semana pasada volvieron a pasar por televisi\u00f3n la pel\u00edcula de cine Hackers con Angelina Jolie y Jonny Lee Miller. Al volver a verla me acord\u00e9 de que el a\u00f1o pasado estuve buscando informaci\u00f3n sobre la chaqueta de moto que lleva Angelina Jolie casi a mitad de la pel\u00edcula. La informaci\u00f3n que encontr\u00e9 ven\u00eda de [&hellip;]","og_url":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\/","og_site_name":"Motocicletas Suzuki","article_published_time":"2011-06-02T18:49:29+00:00","og_image":[{"width":670,"height":126,"url":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2023\/09\/suzuki-motorcycles-logo.png","type":"image\/png"}],"author":"Suzuki Motocicletas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Suzuki Motocicletas","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\/#article","isPartOf":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\/"},"author":{"name":"Suzuki Motocicletas","@id":"https:\/\/servicemanualsgsxr.com\/es\/#\/schema\/person\/b2452f1f1c397049f68165f3dd829646"},"headline":"Chaqueta de moto Suzuki en la pelicula Hackers con Angelina Jolie","datePublished":"2011-06-02T18:49:29+00:00","mainEntityOfPage":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\/"},"wordCount":760,"publisher":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/#organization"},"image":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\/#primaryimage"},"thumbnailUrl":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2011\/06\/angelina-jolie-hackers-3.jpg","keywords":["barry sheene"],"articleSection":["Curiosos","Suzuki en el cine"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\/","url":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\/","name":"Chaqueta de moto Suzuki en la pelicula Hackers con Angelina Jolie | Motocicletas Suzuki","isPartOf":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\/#primaryimage"},"image":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\/#primaryimage"},"thumbnailUrl":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2011\/06\/angelina-jolie-hackers-3.jpg","datePublished":"2011-06-02T18:49:29+00:00","breadcrumb":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\/#primaryimage","url":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2011\/06\/angelina-jolie-hackers-3.jpg","contentUrl":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2011\/06\/angelina-jolie-hackers-3.jpg","width":800,"height":523,"caption":"Angelina Jolie en la pelicula Hackers"},{"@type":"BreadcrumbList","@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/chaqueta-de-moto-suzuki-en-la-pelicula-hackers-con-angelina-jolie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/servicemanualsgsxr.com\/es\/"},{"@type":"ListItem","position":2,"name":"Chaqueta de moto Suzuki en la pelicula Hackers con Angelina Jolie"}]},{"@type":"WebSite","@id":"https:\/\/servicemanualsgsxr.com\/es\/#website","url":"https:\/\/servicemanualsgsxr.com\/es\/","name":"Motocicletas Suzuki","description":"Noticias, informaci\u00f3n y fichas t\u00e9cnicas de motocicletas Suzuki en los modelos deportivas, carretera, trail sport turismo, scooter, cruiser, motocross y enduro","publisher":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/servicemanualsgsxr.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/servicemanualsgsxr.com\/es\/#organization","name":"Motocicletas Suzuki","url":"https:\/\/servicemanualsgsxr.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/servicemanualsgsxr.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2023\/09\/suzuki-motorcycles-logo.png","contentUrl":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2023\/09\/suzuki-motorcycles-logo.png","width":670,"height":126,"caption":"Motocicletas Suzuki"},"image":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/servicemanualsgsxr.com\/es\/#\/schema\/person\/b2452f1f1c397049f68165f3dd829646","name":"Suzuki Motocicletas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g","caption":"Suzuki Motocicletas"},"sameAs":["https:\/\/servicemanualsgsxr.com\/es"],"url":"https:\/\/servicemanualsgsxr.com\/es\/author\/root\/"}]}},"_links":{"self":[{"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/posts\/5168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/comments?post=5168"}],"version-history":[{"count":0,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/posts\/5168\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/media\/5177"}],"wp:attachment":[{"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/media?parent=5168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/categories?post=5168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/tags?post=5168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}