{"id":5152,"date":"2011-06-10T15:31:21","date_gmt":"2011-06-10T13:31:21","guid":{"rendered":"https:\/\/dev.servicemanualsgsxr.com\/?p=20489"},"modified":"2011-06-10T15:31:21","modified_gmt":"2011-06-10T13:31:21","slug":"descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon","status":"publish","type":"post","link":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\/","title":{"rendered":"Descarga de cat\u00e1logos de motos Suzuki GSXR en Jap\u00f3n"},"content":{"rendered":"<p style=\"text-align: justify;\">Buscando informaci\u00f3n por Jap\u00f3n de futuros modelos de <strong>motos Suzuki GSXR<\/strong>, me he encontrado con la web de <strong>MotoMap<\/strong>, un distribuidor oficial de Suzuki que adem\u00e1s tiene un equipo de competici\u00f3n en las categorias <strong>JSB1000 Japan Superbike<\/strong> con una <strong>Suzuki GSXR 1000<\/strong> y en la <strong>ST600 Stock<\/strong> con una <strong>Suzuki GSXR 600<\/strong>.<\/p>\n<p style=\"text-align: justify;\">En esta web he localizado una serie de cat\u00e1logos de motos Suzuki GSXR de los \u00faltimos a\u00f1os en japon\u00e9s, pero son ideales para todos aquellos coleccionistas de cat\u00e1logos, porque no son muy vistos por este lado del mundo.<\/p>\n<p style=\"text-align: justify;\">Podemos bajarnos los cat\u00e1logos en formato pdf de las motos Suzuki GSXR 600, Suzuki GSXR 750, Suzuki GSXR 1000 y Suzuki GSXR 1300 Hayabusa desde el a\u00f1o 2007 hasta el a\u00f1o 2010. Estoy todav\u00eda en espera de que suban los cat\u00e1logos oficiales en japon\u00e9s para las motos Suzuki GSXR 2011, pero estar\u00e1n al caer.<\/p>\n<p style=\"text-align: justify;\">Os dejo con el enlace de la p\u00e1gina de descargas de los cat\u00e1logos: <strong>MotoMap<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buscando informaci\u00f3n por Jap\u00f3n de futuros modelos de motos Suzuki GSXR, me he encontrado con la web de MotoMap, un distribuidor oficial de Suzuki que adem\u00e1s tiene un equipo de competici\u00f3n en las categorias JSB1000 Japan Superbike con una Suzuki GSXR 1000 y en la ST600 Stock con una Suzuki GSXR 600. En esta web [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5153,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[247,31],"tags":[112],"class_list":["post-5152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades","category-motos","tag-japon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Descarga de cat\u00e1logos de motos Suzuki GSXR en Jap\u00f3n | Motocicletas Suzuki<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Descarga de cat\u00e1logos de motos Suzuki GSXR en Jap\u00f3n | Motocicletas Suzuki\" \/>\n<meta property=\"og:description\" content=\"Buscando informaci\u00f3n por Jap\u00f3n de futuros modelos de motos Suzuki GSXR, me he encontrado con la web de MotoMap, un distribuidor oficial de Suzuki que adem\u00e1s tiene un equipo de competici\u00f3n en las categorias JSB1000 Japan Superbike con una Suzuki GSXR 1000 y en la ST600 Stock con una Suzuki GSXR 600. En esta web [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\/\" \/>\n<meta property=\"og:site_name\" content=\"Motocicletas Suzuki\" \/>\n<meta property=\"article:published_time\" content=\"2011-06-10T13:31:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2023\/09\/suzuki-motorcycles-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" \/>\n\t<meta property=\"og:image:height\" content=\"126\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Suzuki Motocicletas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Suzuki Motocicletas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\\\/\"},\"author\":{\"name\":\"Suzuki Motocicletas\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#\\\/schema\\\/person\\\/b2452f1f1c397049f68165f3dd829646\"},\"headline\":\"Descarga de cat\u00e1logos de motos Suzuki GSXR en Jap\u00f3n\",\"datePublished\":\"2011-06-10T13:31:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\\\/\"},\"wordCount\":177,\"publisher\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/catalogo-motos-suzuki-gsxr-japon.jpg\",\"keywords\":[\"japon\"],\"articleSection\":[\"Curiosos\",\"Motos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\\\/\",\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\\\/\",\"name\":\"Descarga de cat\u00e1logos de motos Suzuki GSXR en Jap\u00f3n | Motocicletas Suzuki\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/catalogo-motos-suzuki-gsxr-japon.jpg\",\"datePublished\":\"2011-06-10T13:31:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/catalogo-motos-suzuki-gsxr-japon.jpg\",\"contentUrl\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/catalogo-motos-suzuki-gsxr-japon.jpg\",\"width\":800,\"height\":345,\"caption\":\"catalogos motos suzuki gsx-r en japon\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/curiosidades\\\/motos\\\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descarga de cat\u00e1logos de motos Suzuki GSXR en Jap\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/\",\"name\":\"Motocicletas Suzuki\",\"description\":\"Noticias, informaci\u00f3n y fichas t\u00e9cnicas de motocicletas Suzuki en los modelos deportivas, carretera, trail sport turismo, scooter, cruiser, motocross y enduro\",\"publisher\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#organization\",\"name\":\"Motocicletas Suzuki\",\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/suzuki-motorcycles-logo.png\",\"contentUrl\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/suzuki-motorcycles-logo.png\",\"width\":670,\"height\":126,\"caption\":\"Motocicletas Suzuki\"},\"image\":{\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/#\\\/schema\\\/person\\\/b2452f1f1c397049f68165f3dd829646\",\"name\":\"Suzuki Motocicletas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g\",\"caption\":\"Suzuki Motocicletas\"},\"sameAs\":[\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\"],\"url\":\"https:\\\/\\\/servicemanualsgsxr.com\\\/es\\\/author\\\/root\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Descarga de cat\u00e1logos de motos Suzuki GSXR en Jap\u00f3n | Motocicletas Suzuki","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\/","og_locale":"es_ES","og_type":"article","og_title":"Descarga de cat\u00e1logos de motos Suzuki GSXR en Jap\u00f3n | Motocicletas Suzuki","og_description":"Buscando informaci\u00f3n por Jap\u00f3n de futuros modelos de motos Suzuki GSXR, me he encontrado con la web de MotoMap, un distribuidor oficial de Suzuki que adem\u00e1s tiene un equipo de competici\u00f3n en las categorias JSB1000 Japan Superbike con una Suzuki GSXR 1000 y en la ST600 Stock con una Suzuki GSXR 600. En esta web [&hellip;]","og_url":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\/","og_site_name":"Motocicletas Suzuki","article_published_time":"2011-06-10T13:31:21+00:00","og_image":[{"width":670,"height":126,"url":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2023\/09\/suzuki-motorcycles-logo.png","type":"image\/png"}],"author":"Suzuki Motocicletas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Suzuki Motocicletas","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\/#article","isPartOf":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\/"},"author":{"name":"Suzuki Motocicletas","@id":"https:\/\/servicemanualsgsxr.com\/es\/#\/schema\/person\/b2452f1f1c397049f68165f3dd829646"},"headline":"Descarga de cat\u00e1logos de motos Suzuki GSXR en Jap\u00f3n","datePublished":"2011-06-10T13:31:21+00:00","mainEntityOfPage":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\/"},"wordCount":177,"publisher":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/#organization"},"image":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\/#primaryimage"},"thumbnailUrl":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2011\/06\/catalogo-motos-suzuki-gsxr-japon.jpg","keywords":["japon"],"articleSection":["Curiosos","Motos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\/","url":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\/","name":"Descarga de cat\u00e1logos de motos Suzuki GSXR en Jap\u00f3n | Motocicletas Suzuki","isPartOf":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\/#primaryimage"},"image":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\/#primaryimage"},"thumbnailUrl":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2011\/06\/catalogo-motos-suzuki-gsxr-japon.jpg","datePublished":"2011-06-10T13:31:21+00:00","breadcrumb":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\/#primaryimage","url":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2011\/06\/catalogo-motos-suzuki-gsxr-japon.jpg","contentUrl":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2011\/06\/catalogo-motos-suzuki-gsxr-japon.jpg","width":800,"height":345,"caption":"catalogos motos suzuki gsx-r en japon"},{"@type":"BreadcrumbList","@id":"https:\/\/servicemanualsgsxr.com\/es\/curiosidades\/motos\/descarga-de-catalogos-de-motos-suzuki-gsxr-en-japon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/servicemanualsgsxr.com\/es\/"},{"@type":"ListItem","position":2,"name":"Descarga de cat\u00e1logos de motos Suzuki GSXR en Jap\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/servicemanualsgsxr.com\/es\/#website","url":"https:\/\/servicemanualsgsxr.com\/es\/","name":"Motocicletas Suzuki","description":"Noticias, informaci\u00f3n y fichas t\u00e9cnicas de motocicletas Suzuki en los modelos deportivas, carretera, trail sport turismo, scooter, cruiser, motocross y enduro","publisher":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/servicemanualsgsxr.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/servicemanualsgsxr.com\/es\/#organization","name":"Motocicletas Suzuki","url":"https:\/\/servicemanualsgsxr.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/servicemanualsgsxr.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2023\/09\/suzuki-motorcycles-logo.png","contentUrl":"https:\/\/servicemanualsgsxr.com\/es\/wp-content\/uploads\/2023\/09\/suzuki-motorcycles-logo.png","width":670,"height":126,"caption":"Motocicletas Suzuki"},"image":{"@id":"https:\/\/servicemanualsgsxr.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/servicemanualsgsxr.com\/es\/#\/schema\/person\/b2452f1f1c397049f68165f3dd829646","name":"Suzuki Motocicletas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/981a5def2f1be828444400f539b770cc31b7cb6754c855753f59abb58aefeec2?s=96&d=mm&r=g","caption":"Suzuki Motocicletas"},"sameAs":["https:\/\/servicemanualsgsxr.com\/es"],"url":"https:\/\/servicemanualsgsxr.com\/es\/author\/root\/"}]}},"_links":{"self":[{"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/posts\/5152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/comments?post=5152"}],"version-history":[{"count":0,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/posts\/5152\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/media\/5153"}],"wp:attachment":[{"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/media?parent=5152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/categories?post=5152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/servicemanualsgsxr.com\/es\/wp-json\/wp\/v2\/tags?post=5152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}